{"id":591,"date":"2026-02-18T07:14:09","date_gmt":"2026-02-18T07:14:09","guid":{"rendered":"https:\/\/cfder.org\/?p=591"},"modified":"2026-02-18T07:14:09","modified_gmt":"2026-02-18T07:14:09","slug":"how-to-make-exit-tickets-that-take-1-minute","status":"publish","type":"post","link":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/","title":{"rendered":"So machen Sie Ausfahrtstickets, die 1 Minute dauern"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><section>\n<h2>Warum 1-min\u00fctige Ausfahrt Tickets wichtig sind<\/h2>\n<p>Moderne Klassenzimmer sind schnell und kognitiv anspruchsvoll. Die Lehrer brauchen schnelle Feedback-Schleifen, und die Sch\u00fcler brauchen niedrige Druckm\u00f6glichkeiten, um \u00fcber das Lernen nachzudenken. Kurze Exit-Tickets finden dieses Gleichgewicht perfekt: Sie sammeln aussagekr\u00e4ftige Daten, ohne \u00fcberw\u00e4ltigende Sch\u00fcler oder Lehrer.<\/p>\n<p>Untersuchungen zur formativen Bewertung zeigen, dass h\u00e4ufige, leichte Check-ins das Lernen mehr verbessern als seltene Bewertungen mit hohen Eins\u00e4tzen. Ein gut gestaltetes 1-Minuten-Ausfahrtticket wird zu einer kleinen t\u00e4glichen Gewohnheit, die Unterricht, Metakognition und Unterrichtskultur st\u00e4rkt.<\/p>\n<\/section>\n<section>\n<h2>Was ein Ausfahrtticket ausmacht, dauert nur eine Minute<\/h2>\n<h3>Eine klare Eingabeaufforderung<\/h3>\n<p>Die Sch\u00fcler sollten die Frage in Sekundenschnelle lesen und verstehen. Vermeiden Sie mehrteilige Eingabeaufforderungen oder etwas, das lange Erkl\u00e4rungen erfordert. Eine fokussierte Frage liefert sauberere und umsetzbarere Daten.<\/p>\n<h3>Minimales oder null Schreiben<\/h3>\n<p>Die schnellsten Austrittskarten st\u00fctzen sich auf einzelne W\u00f6rter, kurze S\u00e4tze, Zahlen, Bewertungen oder Emojis. Diese Formate reduzieren die kognitive Belastung und liefern klarere Muster bei den Antworten.<\/p>\n<h3>Geringe kognitive Nachfrage<\/h3>\n<p>Bei Exit-Tickets sollten<em>das heutige<\/em>-Lernen bewertet werden, nicht die allgemeine R\u00fcckruf- oder Testleistung. Die Sch\u00fcler sollten nicht ihr Ged\u00e4chtnis suchen m\u00fcssen. Sie sollten einfach reagieren, reflektieren oder bewerten.<\/p>\n<\/section>\n<section>\n<h2>Die vier Zwecke von 1-Minuten-Ausfahrtstickets<\/h2>\n<h3>1. \u00dcberpr\u00fcfen Sie das Verst\u00e4ndnis<\/h3>\n<p>Ein kurzer Schnappschuss, wie gut die Sch\u00fcler das Konzept des Tages verstanden haben. Selbst eine Ein-Wort-Zusammenfassung oder eine Vertrauensbewertung gibt an, ob eine Neulehre erforderlich ist.<\/p>\n<h3>2. \u00dcberpr\u00fcfen Sie Engagement und Emotionen<\/h3>\n<p>Die Energie, Angst oder das Interesse der Sch\u00fcler wirken sich stark auf das Lernen aus. Ein einfaches Emoji oder eine Skala kann verborgene Muster aufdecken, die die Dynamik des Klassenzimmers beeinflussen.<\/p>\n<h3>3. Informieren Sie die Anweisungen von morgen<\/h3>\n<p>Exit-Tickets helfen den Lehrern, Beispiele, Tempo, Gruppierung oder Neuunterricht f\u00fcr den n\u00e4chsten Tag anzupassen. Eine Minute heute kann morgen zehn Minuten sparen.<\/p>\n<h3>4. Bauen Sie eine Gewohnheit des Nachdenkens auf<\/h3>\n<p>Wenn die Sch\u00fcler &#8211; kurz und ohne Druck &#8211; regelm\u00e4\u00dfig nachdenken, st\u00e4rken sie das metakognitive Bewusstsein und \u00fcbernehmen mehr Eigenverantwortung f\u00fcr ihr Lernen.<\/p>\n<\/section>\n<section>\n<h2>Die besten 1-Minuten-Ausfahrt-Ticketformate<\/h2>\n<h3>Vollst\u00e4ndiger Satz<\/h3>\n<p>Beispiele:<\/p>\n<ul>\n<li>&#8220;Heute habe ich gelernt &#8230;&#8221;<\/li>\n<li>&#8220;Eine Sache, die ich immer noch frage, ist &#8230;&#8221;<\/li>\n<li>&#8220;Etwas, das mir heute geholfen hat, war &#8230;&#8221;<\/li>\n<\/ul>\n<p>Ideal f\u00fcr die F\u00f6rderung der Reflexion, ohne dass lange geschrieben werden muss.<\/p>\n<h3>Schnelle Skalen<\/h3>\n<p>Beispiele:<\/p>\n<ul>\n<li>&#8220;Bewerten Sie Ihr Verst\u00e4ndnis von 1 bis 5.&#8221;<\/li>\n<li>\u201eVertrauen: ja \/ vielleicht \/ noch nicht.\u201c<\/li>\n<li>&#8220;Wie herausfordernd war das heutige Thema? (0\u20133)&#8221;<\/li>\n<\/ul>\n<h3>Multiple-Choice (eine Frage)<\/h3>\n<p>Pr\u00e4sentieren Sie den Sch\u00fclern 2\u20134 einfache Optionen. Dies ist das schnellstm\u00f6gliche Format und ideal, um Missverst\u00e4ndnisse zu \u00fcberpr\u00fcfen.<\/p>\n<h3>Emoji-basiert<\/h3>\n<p>Perfekt f\u00fcr j\u00fcngere Sch\u00fcler, mehrsprachige Klassenzimmer oder bei der Diskussion \u00fcber Emotionen.<\/p>\n<h3>Ein-Wort-Check-ins<\/h3>\n<p>Nach einem einzigen Wort zu fragen, f\u00e4ngt Stimmung, Klarheit oder Engagement mit \u00fcberraschender Tiefe ein.<\/p>\n<\/section>\n<section>\n<h2>30 1-Minuten-Ausfahrtsticket-Eingabeaufforderung<\/h2>\n<h3>Verst\u00e4ndnis<\/h3>\n<ul>\n<li>\u201eDie wichtigste Idee heute war\u2026\u201c<\/li>\n<li>&#8220;Eine Sache, die ich jetzt erkl\u00e4ren kann, ist &#8230;&#8221;<\/li>\n<li>&#8220;Ein Teil, den ich immer noch verwirrend finde, ist &#8230;&#8221;<\/li>\n<\/ul>\n<h3>Vertrauen<\/h3>\n<ul>\n<li>\u201eVertrauensstufe (1\u20135): ___\u201c<\/li>\n<li>&#8220;Ich kann Probleme wie heute machen: ja \/ vielleicht \/ noch nicht.&#8221;<\/li>\n<li>\u201eDie heutige Lektion hat Sinn gemacht: \ud83d\udc4d \/ \ud83e\udd14 \/ \ud83d\udc4e\u201c<\/li>\n<\/ul>\n<h3>Missverst\u00e4ndnisse<\/h3>\n<ul>\n<li>&#8220;Ein Fehler, den man beim n\u00e4chsten Mal vermeiden sollte, ist &#8230;&#8221;<\/li>\n<li>&#8220;Zuerst dachte ich &#8230;, aber jetzt wei\u00df ich &#8230;&#8221;<\/li>\n<li>&#8220;Etwas, das mich heute \u00fcberrascht hat &#8230;&#8221;<\/li>\n<\/ul>\n<h3>Anwendung<\/h3>\n<ul>\n<li>&#8220;Ich k\u00f6nnte die Idee von heute nutzen in &#8230;&#8221;<\/li>\n<li>\u201eDas heutige Konzept verbindet sich mit\u2026\u201c<\/li>\n<li>\u201eEin Beispiel aus der realen Welt ist \u2026\u201c<\/li>\n<\/ul>\n<h3>Engagement<\/h3>\n<ul>\n<li>&#8220;Ich war am konzentriertesten w\u00e4hrend &#8230;&#8221;<\/li>\n<li>&#8220;Einen Moment, den ich interessant fand, war &#8230;&#8221;<\/li>\n<li>Emoji, um die heutige Klasse zu beschreiben: \ud83d\ude00 \ud83d\ude10 \ud83d\ude23<\/li>\n<\/ul>\n<\/section>\n<section>\n<h2>Schneller Vergleich von 1-Minuten-Ausfahrt-Tickettypen<\/h2>\n<table class=\"custom-table\">\n<tbody>\n<tr>\n<th>Format<\/th>\n<th>Zeit ben\u00f6tigt<\/th>\n<th>am besten f\u00fcr<\/th>\n<th>Beispielaufforderung<\/th>\n<\/tr>\n<tr>\n<td>Ein-Wort-Zusammenfassung<\/td>\n<td>5\u201310 Sekunden<\/td>\n<td>Stimmung, Klarheit, Engagement<\/td>\n<td>&#8220;Beschreibe heute in einem Wort.&#8221;<\/td>\n<\/tr>\n<tr>\n<td>Skala (0\u20135)<\/td>\n<td>10 Sekunden<\/td>\n<td>Verst\u00e4ndnis, Vertrauen<\/td>\n<td>&#8220;Bewerten Sie Ihr Verst\u00e4ndnis (1\u20135).&#8221;<\/td>\n<\/tr>\n<tr>\n<td>Emoji-Check-in<\/td>\n<td>5 Sekunden<\/td>\n<td>Sel, emotionales Klima<\/td>\n<td>\ud83d\ude00 \ud83d\ude10 \ud83d\ude23<\/td>\n<\/tr>\n<tr>\n<td>Satzstarter<\/td>\n<td>20\u201330 Sekunden<\/td>\n<td>Reflexion, Synthese<\/td>\n<td>&#8220;Heute habe ich gelernt &#8230;&#8221;<\/td>\n<\/tr>\n<tr>\n<td>Mehrfachauswahl<\/td>\n<td>10\u201320 Sekunden<\/td>\n<td>Missverst\u00e4ndnisse, schnelle Inhaltspr\u00fcfung<\/td>\n<td>\u201eDie Hauptidee war: A \/ B \/ C\u201c<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/section>\n<section>\n<h2>So analysieren Sie Ausfahrtstickets in weniger als f\u00fcnf Minuten<\/h2>\n<p>Die wahre Kraft von Exit-Tickets besteht darin, sie schnell zu interpretieren und die Anweisungen anzupassen. Sie m\u00fcssen nicht jede Antwort ausf\u00fchrlich lesen &#8211; sortieren Sie sie einfach in einfache Kategorien und suchen Sie nach Mustern.<\/p>\n<h3>in drei Eimer sortieren<\/h3>\n<ul>\n<li><strong>verstanden<\/strong><\/li>\n<li><strong>Art von<\/strong><\/li>\n<li><strong>Noch nicht<\/strong><\/li>\n<\/ul>\n<h3>Suchen Sie nach wiederholten Mustern<\/h3>\n<p>Wenn f\u00fcnf oder mehr Sch\u00fcler die gleiche Verwirrung erw\u00e4hnen, ist dies ein starkes Signal. Eine dreimin\u00fctige Wiederholung oder ein zus\u00e4tzliches Beispiel am n\u00e4chsten Tag l\u00f6st das Problem h\u00e4ufig sofort.<\/p>\n<h3>kleine Anpassungen vornehmen<\/h3>\n<p>Das Aufw\u00e4rmen von morgen kann auf das h\u00e4ufigste Missverst\u00e4ndnis abzielen. Die Gruppierungsstrategien oder das Tempo k\u00f6nnen sich leicht verschieben. Diese Mikroanpassungen verst\u00e4rken sich im Laufe der Zeit und verbessern die Lernergebnisse erheblich.<\/p>\n<\/section>\n<section>\n<h2>Digitale Tools f\u00fcr einmin\u00fctige Ausfahrtstickets<\/h2>\n<p>Die Technologie macht schnelle Ausstiegskarten noch schneller zu sammeln und zu analysieren. Viele Tools unterst\u00fctzen Einzelfragenformate, die sich ideal f\u00fcr die 1-Minuten-Nutzung eignen.<\/p>\n<h3>Google Forms<\/h3>\n<p>Perfekt f\u00fcr automatisierte Charts und Sortierung. Ein Formular mit einer Frage kann sofortige visuelle Zusammenfassungen liefern.<\/p>\n<h3>Mentimeter, Slido, Kahoot<\/h3>\n<p>Diese Polling-Tools erstellen Echtzeitdaten und eignen sich hervorragend f\u00fcr gr\u00f6\u00dfere Klassen.<\/p>\n<h3>LMS-Schnellpr\u00fcfungen<\/h3>\n<p>Canvas, SchooloGy und Moodle bieten integrierte Mikro-Assessments, die sich leicht in die t\u00e4glichen Routinen einf\u00fcgen.<\/p>\n<h3>KI-gest\u00fctzte Kategorisierung (ethische Verwendung)<\/h3>\n<p>Sie k\u00f6nnen 100 kurze Antworten in ein KI-Tool einf\u00fcgen und es bitten, sie in Themen zu gruppieren &#8211; solange Sie keine pers\u00f6nlichen Informationen enthalten und die Schulrichtlinien befolgen.<\/p>\n<\/section>\n<section>\n<h2>H\u00e4ufige Fehler beim Erstellen von Exit-Tickets<\/h2>\n<h3>Zu viele Fragen<\/h3>\n<p>Ein echtes 1-Minuten-Ausfahrtsticket enth\u00e4lt nur eine Eingabeaufforderung. Mehr als das ruiniert das Format.<\/p>\n<h3>Es f\u00fchlt sich wie ein Test an<\/h3>\n<p>Exit-Tickets sollten niedrig und unterst\u00fctzend sein, niemals bewertend. Vermeiden Sie es, sie zu bewerten oder die Formulierung im Teststil zu verwenden.<\/p>\n<h3>nicht auf die Daten reagieren<\/h3>\n<p>Wenn die Sch\u00fcler nie sehen, dass Sie ihr Feedback verwenden, nehmen sie die Ausreisetickets nicht ernst. Schon eine schnelle Best\u00e4tigung am n\u00e4chsten Tag h\u00e4lt den Zyklus sinnvoll.<\/p>\n<\/section>\n<section>\n<h2>Gebrauchsfertige 1-Minuten-Ausfahrt-Ticket-Vorlagen<\/h2>\n<ul>\n<li><strong>Vorlage 1:<\/strong> \u201eBewerten Sie Ihr Verst\u00e4ndnis (1\u20135).\u201c<\/li>\n<li><strong>Vorlage 2:<\/strong> \u201eHeute habe ich gelernt\u2026\u201c<\/li>\n<li><strong>Template 3:<\/strong> Emoji Mood Check.<\/li>\n<li><strong>Template 4:<\/strong> \u201cEine Sache, die ich immer noch wundere, ist\u2026\u201d<\/li>\n<li><strong>Vorlage 5:<\/strong> \u201cDas Schwierigste war heute\u2026\u201d<\/li>\n<\/ul>\n<\/section>\n<section>\n<h2>Fazit: Kleine Gewohnheit, gro\u00dfe Wirkung<\/h2>\n<p>Ein-Minuten-Ausfahrttickets sind eines der einfachsten und wirkungsvollsten Werkzeuge, die ein Lehrer verwenden kann. Sie nehmen sich fast keine Zeit, senken den Stress f\u00fcr die Sch\u00fcler und generieren Erkenntnisse, die den Unterricht sinnvoll gestalten. Wenn sie konsequent eingesetzt werden, bauen sie eine reflektierende Unterrichtskultur auf und bef\u00e4higen die Sch\u00fcler, ihre Bed\u00fcrfnisse klar zu kommunizieren. Kleine Gewohnheit &#8211; riesige Auszahlung.<\/p>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Warum 1-min\u00fctige Ausfahrt Tickets wichtig sind Moderne Klassenzimmer sind schnell und kognitiv anspruchsvoll. Die Lehrer brauchen schnelle Feedback-Schleifen, und die Sch\u00fcler brauchen niedrige Druckm\u00f6glichkeiten, um \u00fcber das Lernen nachzudenken. Kurze Exit-Tickets finden dieses Gleichgewicht perfekt: Sie sammeln aussagekr\u00e4ftige Daten, ohne \u00fcberw\u00e4ltigende Sch\u00fcler oder Lehrer. Untersuchungen zur formativen Bewertung zeigen, dass h\u00e4ufige, leichte Check-ins das Lernen [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_locale":"de_DE","_original_post":"https:\/\/cfder.org\/?p=212","footnotes":""},"categories":[2],"tags":[],"class_list":["post-591","post","type-post","status-publish","format-standard","hentry","category-formative-assessment-and-feedback-strategies","de-DE"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>So machen Sie Ausfahrtstickets, die 1 Minute dauern<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie Sie schnelle und effektive 1-min\u00fctige Ausstiegskarten entwerfen, die das Verst\u00e4ndnis der Sch\u00fcler vermitteln, die Reflexion verbessern und den Unterricht verbessern - ohne die Einstufungszeit zu erh\u00f6hen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So machen Sie Ausfahrtstickets, die 1 Minute dauern\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie Sie schnelle und effektive 1-min\u00fctige Ausstiegskarten entwerfen, die das Verst\u00e4ndnis der Sch\u00fcler vermitteln, die Reflexion verbessern und den Unterricht verbessern - ohne die Einstufungszeit zu erh\u00f6hen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/\" \/>\n<meta property=\"og:site_name\" content=\"Cfder.org\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T07:14:09+00:00\" \/>\n<meta name=\"author\" content=\"Maya Patel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maya Patel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So machen Sie Ausfahrtstickets, die 1 Minute dauern","description":"Erfahren Sie, wie Sie schnelle und effektive 1-min\u00fctige Ausstiegskarten entwerfen, die das Verst\u00e4ndnis der Sch\u00fcler vermitteln, die Reflexion verbessern und den Unterricht verbessern - ohne die Einstufungszeit zu erh\u00f6hen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/","og_locale":"de_DE","og_type":"article","og_title":"So machen Sie Ausfahrtstickets, die 1 Minute dauern","og_description":"Erfahren Sie, wie Sie schnelle und effektive 1-min\u00fctige Ausstiegskarten entwerfen, die das Verst\u00e4ndnis der Sch\u00fcler vermitteln, die Reflexion verbessern und den Unterricht verbessern - ohne die Einstufungszeit zu erh\u00f6hen.","og_url":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/","og_site_name":"Cfder.org","article_published_time":"2026-02-18T07:14:09+00:00","author":"Maya Patel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Maya Patel","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/#article","isPartOf":{"@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/"},"author":{"name":"Maya Patel","@id":"https:\/\/www.cfder.org\/#\/schema\/person\/0ffdf37b1e6ae836daf26f750dd959f3"},"headline":"So machen Sie Ausfahrtstickets, die 1 Minute dauern","datePublished":"2026-02-18T07:14:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/"},"wordCount":1086,"commentCount":0,"articleSection":["Formative Bewertungs- und Feedback-Strategien"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/","url":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/","name":"So machen Sie Ausfahrtstickets, die 1 Minute dauern","isPartOf":{"@id":"https:\/\/www.cfder.org\/#website"},"datePublished":"2026-02-18T07:14:09+00:00","author":{"@id":"https:\/\/www.cfder.org\/#\/schema\/person\/0ffdf37b1e6ae836daf26f750dd959f3"},"description":"Erfahren Sie, wie Sie schnelle und effektive 1-min\u00fctige Ausstiegskarten entwerfen, die das Verst\u00e4ndnis der Sch\u00fcler vermitteln, die Reflexion verbessern und den Unterricht verbessern - ohne die Einstufungszeit zu erh\u00f6hen.","breadcrumb":{"@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cfder.org\/de\/how-to-make-exit-tickets-that-take-1-minute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cfder.org\/"},{"@type":"ListItem","position":2,"name":"So machen Sie Ausfahrtstickets, die 1 Minute dauern"}]},{"@type":"WebSite","@id":"https:\/\/www.cfder.org\/#website","url":"https:\/\/www.cfder.org\/","name":"Cfder.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cfder.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.cfder.org\/#\/schema\/person\/0ffdf37b1e6ae836daf26f750dd959f3","name":"Maya Patel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5fc40e2249c256c81b2c32ccc19285b8d7d0052898e180a7a52fb7af4c28e35b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fc40e2249c256c81b2c32ccc19285b8d7d0052898e180a7a52fb7af4c28e35b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fc40e2249c256c81b2c32ccc19285b8d7d0052898e180a7a52fb7af4c28e35b?s=96&d=mm&r=g","caption":"Maya Patel"},"sameAs":["https:\/\/bizzrepublic.com\/"],"url":"https:\/\/www.cfder.org\/author\/maya-patel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/posts\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/comments?post=591"}],"version-history":[{"count":1,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/posts\/591\/revisions"}],"predecessor-version":[{"id":693,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/posts\/591\/revisions\/693"}],"wp:attachment":[{"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/media?parent=591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/categories?post=591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfder.org\/wp-json\/wp\/v2\/tags?post=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}